{"id":575,"date":"2023-12-04T21:24:44","date_gmt":"2023-12-04T21:24:44","guid":{"rendered":"https:\/\/koramare.it\/?post_type=product&#038;p=575"},"modified":"2025-03-24T16:47:30","modified_gmt":"2025-03-24T15:47:30","slug":"huile-essentielle-de-mandarine-biologique","status":"publish","type":"product","link":"https:\/\/koramare.it\/fr\/huile-essentielle-de-mandarine-biologique\/","title":{"rendered":"Huile Essentielle de Mandarine Biologique(10ml)"},"content":{"rendered":"<p>L'huile essentielle de bergamote poss\u00e8de de puissantes propri\u00e9t\u00e9s antiseptiques, anti-infectieuses et cicatrisantes, ce qui la rend id\u00e9ale pour traiter les probl\u00e8mes de peau, les plaies et diverses dermatoses. La bergamote est apaisante et s\u00e9dative, comme la plupart des huiles essentielles d'agrumes, et est \u00e9galement reconnue pour lutter contre le stress et l'insomnie.<\/p>\n<p><b>Propri\u00e9t\u00e9s des huiles essentielles: <span style=\"font-weight: 400;\">Antiseptique et antiviral gr\u00e2ce \u00e0 sa teneur en limon\u00e8ne, s\u00e9datif contre l'anxi\u00e9t\u00e9, il aide \u00e0 induire le sommeil chez les enfants lorsqu'il est diffus\u00e9 dans l'environnement.\u00a0<\/span><\/b><\/p>\n<p>Suggestions de pr\u00e9sentation: <span style=\"font-weight: 400;\">Utilisez-le dans un diffuseur d'air pour parfumer agr\u00e9ablement la pi\u00e8ce. Il peut \u00e9galement \u00eatre utilis\u00e9 dans le bain pour un effet relaxant, dans le bac \u00e0 eau ou pour parfumer vos produits d'entretien. Vous pouvez aussi d\u00e9poser quelques gouttes sur un mouchoir et les inhaler au besoin pour att\u00e9nuer le stress.\u00a0<\/span><\/p>\n<p><b>Pr\u00e9cautions d'emploi<\/b><span style=\"font-weight: 400;\">: \u00c9viter tout contact avec les yeux. Tenir hors de port\u00e9e des enfants. Contient des mol\u00e9cules photosensibilisantes\u00a0; ne pas exposer la peau au soleil apr\u00e8s utilisation.<\/span><\/p>\n<p><b>Instructions de stockage<\/b>: Il est pr\u00e9f\u00e9rable de conserver les huiles essentielles dans un endroit frais et sec, \u00e0 l'abri de la lumi\u00e8re et de la chaleur. Les huiles essentielles d'agrumes sont plus sensibles \u00e0 l'oxydation que les autres huiles essentielles.<\/p>","protected":false},"excerpt":{"rendered":"<p>L'huile essentielle de mandarine a une couleur jaune-orange et un parfum frais, acidul\u00e9 et aromatique.<br \/>\nElle stimule la bonne humeur et l'envie d'entreprendre. L'huile essentielle d'orange est extraite \u00e0 froid des \u00e9corces d'orange.<\/p>\n<p><strong>Produit certifi\u00e9 biologique, pour un usage environnemental.<\/strong><\/p>\n<p><b>Nom<\/b><span style=\"font-weight: 400;\">: Huile essentielle de mandarine biologique<br \/>\n<\/span><b>Ingr\u00e9dients<\/b>: Mandarine 100% bio<br \/>\n<b>Processus de production: <\/b>Extraction \u00e0 froid. Huile essentielle 100 % pure et naturelle, non dilu\u00e9e et non rectifi\u00e9e, au parfum doux et fruit\u00e9.<br \/>\n<b>Origine des mati\u00e8res premi\u00e8res<\/b><span style=\"font-weight: 400;\">: Mandarin : Italie<br \/>\n<\/span><b>Principaux composants actifs: <\/b><span style=\"font-weight: 400;\">Limon\u00e8ne (60-80%), gamma-terpin\u00e8ne (12-22%), alpha-pin\u00e8ne (1-4%)<br \/>\n<\/span><b>Dur\u00e9e de conservation: <\/b>12 mois apr\u00e8s l'ouverture<br \/>\n<strong>Contenu<\/strong>: 10ml<\/p>","protected":false},"featured_media":313,"comment_status":"open","ping_status":"closed","template":"","meta":[],"product_brand":[],"product_cat":[19],"product_tag":[],"class_list":{"0":"post-575","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-olio-essenziale","8":"first","9":"outofstock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/product\/575","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/comments?post=575"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/media\/313"}],"wp:attachment":[{"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/media?parent=575"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/product_brand?post=575"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/product_cat?post=575"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/koramare.it\/fr\/wp-json\/wp\/v2\/product_tag?post=575"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}